{"id":19623,"date":"2020-01-03T10:00:39","date_gmt":"2020-01-03T10:00:39","guid":{"rendered":"https:\/\/robertcutty.com\/?p=19623"},"modified":"2020-01-10T11:12:28","modified_gmt":"2020-01-10T11:12:28","slug":"bambini-e-verdura-una-causa-vinta","status":"publish","type":"post","link":"https:\/\/robertcutty.com\/it\/bambini-e-verdura-una-causa-vinta","title":{"rendered":"Bambini e verdura, una causa vinta"},"content":{"rendered":"<p>L&#8217;inizio dell&#8217;anno nuovo di solito coincide sempre con una sola cosa: tanti nuovi buoni propositi. La maggior parte sono sempre gli stessi &#8211; cominciare ad andare il palestra, spendere meno, bere pi\u00f9 acqua &#8211; ma chi ha dei bimbi si ritrova sempre a dover aggiungere un importantissimo punto alla lista, ovvero quello di riuscire a far mangiare la verdura al proprio bambino.<br \/>\nIl regno di internet \u00e8 pieno di suggerimenti che sostengono di riuscire a trasformare quest&#8217;arduissima impresa in un gioco da ragazzi, e in effetti alcune tecniche riescono davvero nel loro intento.<br \/>\nProprio per questo, abbiamo deciso di raccogliere per voi tutte quelle di maggior successo,cos\u00ec da aiutarvi nella vostra nuova impresa del 2020.<\/p>\n<p>Curiosi di scoprirle tutte? Allora non potete perdervi questo articolo \ud83d\ude09<\/p>\n<h3>Gelatini ai broccoli e salsiccia<\/h3>\n<div id=\"attachment_19635\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-19635\" class=\"size-medium wp-image-19635\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Gelato-salato-ai-broccoli-e-salsiccia-per-bambini-300x225.jpg\" alt=\"Gelato di broccoli e salsiccia per bambini\" width=\"300\" height=\"225\" srcset=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Gelato-salato-ai-broccoli-e-salsiccia-per-bambini-300x225.jpg 300w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Gelato-salato-ai-broccoli-e-salsiccia-per-bambini.jpg 563w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-19635\" class=\"wp-caption-text\">Picture by DonnaModerna<\/p><\/div>\n<p>Quale modo migliore per camuffare la presenza della verdura, se non con la forma di un fantastico stecco di gelato? (Del resto, a chi non piace il gelato..)<br \/>\n<a href=\"https:\/\/ricette.donnamoderna.com\/stecchi-misti-saporiti\">Donna Moderna<\/a> ci regala cos\u00ec una fantastica idea per convincere i bimbi di qualunque et\u00e0 a pensare che i broccoli non siano poi tanto male: dei piccoli gelati fatti con salsiccia e broccoli, una vera delizia per il palato.<\/p>\n<p>La realizzazione di questo piatto \u00e8 molto pi\u00f9 veloce di quello che potrebbe sembrare, e il successo \u00e8 assicurato! Gli ingredienti? Eccoli qui:<\/p>\n<ul id=\"ingredienti-lista\" class=\"ingredienti-lista\">\n<li class=\"ingrediente-singolo\"><span class=\"descrizione-ingrediente\"><span class=\"quantita-ingrediente\">500 gr<\/span>\u00a0salsiccia di maiale<\/span><\/li>\n<li class=\"ingrediente-singolo\"><span class=\"descrizione-ingrediente\"><span class=\"quantita-ingrediente\">150 gr<\/span>\u00a0broccoli<\/span><\/li>\n<li class=\"ingrediente-singolo\"><span class=\"descrizione-ingrediente\"><span class=\"quantita-ingrediente\">150 gr<\/span>\u00a0fontina<\/span><\/li>\n<li class=\"ingrediente-singolo\"><span class=\"descrizione-ingrediente\"><span class=\"quantita-ingrediente\">2 <\/span>albume<\/span><\/li>\n<li class=\"ingrediente-singolo\"><span class=\"descrizione-ingrediente\"><span class=\"quantita-ingrediente\">0.5 dl<\/span>\u00a0latte intero<\/span><\/li>\n<li class=\"ingrediente-singolo\"><span class=\"descrizione-ingrediente\"><span class=\"quantita-ingrediente\">q.b.<\/span>\u00a0frutta secca<\/span><\/li>\n<li class=\"ingrediente-singolo\"><span class=\"descrizione-ingrediente\"><span class=\"quantita-ingrediente\">q.b.<\/span>\u00a0pane grattugiato<\/span><\/li>\n<\/ul>\n<h3>Animali di verdure<\/h3>\n<div id=\"attachment_19636\" style=\"width: 293px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-19636\" class=\" wp-image-19636\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Animali-di-verdura-per-bambini-300x175.jpg\" alt=\"Agnellino di verdura per bambini\" width=\"283\" height=\"165\" srcset=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Animali-di-verdura-per-bambini-300x175.jpg 300w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Animali-di-verdura-per-bambini.jpg 600w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/><p id=\"caption-attachment-19636\" class=\"wp-caption-text\">Picture by videotutorial.it<\/p><\/div>\n<p>Uno dei migliori modi per far piacere le verdure ai bimbi \u00e8 sempre stato e sempre sar\u00e0 quello di trasformarli in piccoli simpatici animali. Ecco che, in questo modo, la verdura diventer\u00e0 improvvisamente un bellissimo gioco, e anche una buonissima pietanza!<\/p>\n<p>La regola qui \u00e8 solo una: dare libero sfogo alla fantasia. Un cavolfiore pu\u00f2 di colpo diventare il corpo soffice di una pecorella, le fragoline possono diventare dei piccoli topini, le banane possono trasformarsi nei lunghi colli delle giraffe, e i kiwi possono assumere le sembianze di simpatiche teste di un gruppo di galletti.<\/p>\n<h3>Sandwich di verdure con la forma dei personaggi dei cartoni<\/h3>\n<div id=\"attachment_19637\" style=\"width: 278px\" class=\"wp-caption alignleft\"><img decoding=\"async\" aria-describedby=\"caption-attachment-19637\" class=\" wp-image-19637\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Sandwich-di-verdure-a-forma-di-pesce-per-bambini.jpg\" alt=\"Sandwich di verdure a forma di pesce\" width=\"268\" height=\"236\" \/><p id=\"caption-attachment-19637\" class=\"wp-caption-text\">Picture by BebeBlog<\/p><\/div>\n<p>Ultima tecnica che riscuote sempre un gran successo \u00e8 quella di camuffare l&#8217;aspetto delle verdure trasformandole nei personaggi preferiti dei propri bambini. Il modo pi\u00f9 semplice per farlo? Un fantastico sandwich!<br \/>\nNiente riesce infatti a far venire fame meglio di un buon vecchio panino, ancora meglio se caratterizzato dai simpatici tratti dei protagonisti dei cartoni animati.<\/p>\n<p>Di nuovo, non dovete far altro che dare spazio alla vostra immaginazione, creando il setting di Nemo in mezzo al mare con un bel piatto azzurro, del film Cars tagliando il pane a forma di macchina, o ancora del Re Leone componendo il pane e la sua imbottitura in modo da dare vita a un leoncino.<\/p>\n<p>Tutti pronti a mettervi ai fornelli?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;inizio dell&#8217;anno nuovo di solito coincide sempre con una sola cosa: tanti nuovi buoni propositi. La maggior parte sono sempre gli stessi &#8211; cominciare ad andare il palestra, spendere meno, bere pi\u00f9 acqua &#8211; ma chi ha dei bimbi si ritrova sempre a dover aggiungere&#8230;<\/p>\n","protected":false},"author":3,"featured_media":19668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":19,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Verdura e bambini: tre ricette per avere successo a tavola - Robert Cutty<\/title>\n<meta name=\"description\" content=\"Siete alla ricerca del metodo perfetto per riuscire a far mangiare la verdura ai vostri bambini? Ecco qualche prezioso consiglio per riuscire nell&#039;impresa!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Verdura e bambini: tre ricette per avere successo a tavola - Robert Cutty\" \/>\n<meta property=\"og:description\" content=\"Siete alla ricerca del metodo perfetto per riuscire a far mangiare la verdura ai vostri bambini? Ecco qualche prezioso consiglio per riuscire nell&#039;impresa!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta\" \/>\n<meta property=\"og:site_name\" content=\"Robert Cutty\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-03T10:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-10T11:12:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Tassoni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Tassoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#article\",\"isPartOf\":{\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta\"},\"author\":{\"name\":\"Giulia Tassoni\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\"},\"headline\":\"Bambini e verdura, una causa vinta\",\"datePublished\":\"2020-01-03T10:00:39+00:00\",\"dateModified\":\"2020-01-10T11:12:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta\"},\"wordCount\":501,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage\"},\"thumbnailUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta\",\"url\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta\",\"name\":\"Verdura e bambini: tre ricette per avere successo a tavola - Robert Cutty\",\"isPartOf\":{\"@id\":\"https:\/\/robertcutty.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage\"},\"image\":{\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage\"},\"thumbnailUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg\",\"datePublished\":\"2020-01-03T10:00:39+00:00\",\"dateModified\":\"2020-01-10T11:12:28+00:00\",\"author\":{\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\"},\"description\":\"Siete alla ricerca del metodo perfetto per riuscire a far mangiare la verdura ai vostri bambini? Ecco qualche prezioso consiglio per riuscire nell'impresa!\",\"breadcrumb\":{\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage\",\"url\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg\",\"contentUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg\",\"width\":876,\"height\":701,\"caption\":\"Verdure per bambini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/robertcutty.com\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bambini e verdura, una causa vinta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/robertcutty.com\/#website\",\"url\":\"https:\/\/robertcutty.com\/\",\"name\":\"Robert Cutty\",\"description\":\"Agenzia di comunicazione ed organizzazione eventi per adulti e bambini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/robertcutty.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\",\"name\":\"Giulia Tassoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g\",\"caption\":\"Giulia Tassoni\"},\"url\":\"https:\/\/robertcutty.com\/it\/author\/giulia-tassoni\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Verdura e bambini: tre ricette per avere successo a tavola - Robert Cutty","description":"Siete alla ricerca del metodo perfetto per riuscire a far mangiare la verdura ai vostri bambini? Ecco qualche prezioso consiglio per riuscire nell'impresa!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta","og_locale":"it_IT","og_type":"article","og_title":"Verdura e bambini: tre ricette per avere successo a tavola - Robert Cutty","og_description":"Siete alla ricerca del metodo perfetto per riuscire a far mangiare la verdura ai vostri bambini? Ecco qualche prezioso consiglio per riuscire nell'impresa!","og_url":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta","og_site_name":"Robert Cutty","article_published_time":"2020-01-03T10:00:39+00:00","article_modified_time":"2020-01-10T11:12:28+00:00","og_image":[{"width":876,"height":701,"url":"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg","type":"image\/jpeg"}],"author":"Giulia Tassoni","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Tassoni","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#article","isPartOf":{"@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta"},"author":{"name":"Giulia Tassoni","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634"},"headline":"Bambini e verdura, una causa vinta","datePublished":"2020-01-03T10:00:39+00:00","dateModified":"2020-01-10T11:12:28+00:00","mainEntityOfPage":{"@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta"},"wordCount":501,"commentCount":0,"image":{"@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage"},"thumbnailUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#respond"]}]},{"@type":"WebPage","@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta","url":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta","name":"Verdura e bambini: tre ricette per avere successo a tavola - Robert Cutty","isPartOf":{"@id":"https:\/\/robertcutty.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage"},"image":{"@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage"},"thumbnailUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg","datePublished":"2020-01-03T10:00:39+00:00","dateModified":"2020-01-10T11:12:28+00:00","author":{"@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634"},"description":"Siete alla ricerca del metodo perfetto per riuscire a far mangiare la verdura ai vostri bambini? Ecco qualche prezioso consiglio per riuscire nell'impresa!","breadcrumb":{"@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#primaryimage","url":"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg","contentUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2020\/01\/Verdure-e-bambini.jpg","width":876,"height":701,"caption":"Verdure per bambini"},{"@type":"BreadcrumbList","@id":"https:\/\/robertcutty.com\/bambini-e-verdura-una-causa-vinta#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robertcutty.com\/it"},{"@type":"ListItem","position":2,"name":"Bambini e verdura, una causa vinta"}]},{"@type":"WebSite","@id":"https:\/\/robertcutty.com\/#website","url":"https:\/\/robertcutty.com\/","name":"Robert Cutty","description":"Agenzia di comunicazione ed organizzazione eventi per adulti e bambini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robertcutty.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634","name":"Giulia Tassoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g","caption":"Giulia Tassoni"},"url":"https:\/\/robertcutty.com\/it\/author\/giulia-tassoni"}]}},"_links":{"self":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/comments?post=19623"}],"version-history":[{"count":5,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19623\/revisions"}],"predecessor-version":[{"id":19639,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19623\/revisions\/19639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/media\/19668"}],"wp:attachment":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/media?parent=19623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/categories?post=19623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/tags?post=19623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}