{"id":19587,"date":"2019-12-13T09:01:28","date_gmt":"2019-12-13T09:01:28","guid":{"rendered":"https:\/\/robertcutty.com\/?p=19587"},"modified":"2019-12-13T09:01:28","modified_gmt":"2019-12-13T09:01:28","slug":"vacanze-di-natale-last-minute","status":"publish","type":"post","link":"https:\/\/robertcutty.com\/it\/vacanze-di-natale-last-minute","title":{"rendered":"3 idee per una vacanza di Natale last minute"},"content":{"rendered":"<p>Natale significa sempre tantissime cose: cibo, stare tra gli amici e in famiglia, lo scambio di regali, e anche qualche meritato giorno di ferie. Che siano di una settimana o solo di qualche giorno, le vacanze sono sempre il pretesto perfetto per staccare un attimo la spina, e concedersi un viaggetto per respirare un&#8217;aria un po&#8217; diversa da quella di casa.<br \/>\nSe la voglia di partire vi sta letteralmente assalendo, ma non siete ancora riusciti a trovare la meta perfetta per voi, non disperatevi.. abbiamo ben tre soluzioni last minute che fanno al caso vostro!<\/p>\n<p>Curiosi di scoprire quali sono? Continuate a leggere, ne abbiamo per tutti i gusti \ud83d\ude0d<\/p>\n<h3>Glamping sulle rive del lago di Bled<\/h3>\n<div id=\"attachment_19588\" style=\"width: 320px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-19588\" class=\" wp-image-19588\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Groupon-300x182.jpg\" alt=\"Capanne Glamping Bled\" width=\"310\" height=\"188\" srcset=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Groupon-300x182.jpg 300w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Groupon.jpg 620w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/><p id=\"caption-attachment-19588\" class=\"wp-caption-text\">Picture by Groupon<\/p><\/div>\n<p>A sole cinque ore e mezza in macchina da Milano, il lago sloveno di Bled \u00e8 uno dei laghi pi\u00f9 magici che si possono trovare in Europa. Con la sua minuscola isoletta in mezzo all&#8217;acqua, questa location attira turisti veramente da tutto il mondo, facendo innamorare alla follia grandi e piccini.<br \/>\n\u00c8 proprio a due passi da qui che si trova il Glamping Ribno, la versione &#8220;glamour&#8221; del classico campeggio. Bungalow dalla forma di minuscole casette in legno, idromassaggio privato proprio davanti alla porta di casa, luci soffuse e un setting da bosco incantato sono gli ingredienti che rendono questo posto il palcoscenico di una vera e propria favola.<br \/>\nPerfetto sia per le vacanze con il vostro gruppo di amici che con la vostra famiglia, potete trovare tutte le informazioni inerenti alla struttura sulla <a href=\"https:\/\/www.booking.com\/hotel\/si\/glamping-ribno.it.html?aid=311091&amp;label=glamping-ribno-qskZ9tDU3Qf2WnJyaQT%2AnAS161704194406%3Apl%3Ata%3Ap1%3Ap2%3Aac%3Aap1t2%3Aneg%3Afi%3Atiaud-285284111406%3Akwd-312037143119%3Alp1008463%3Ali%3Adec%3Adm&amp;sid=a087d29763012d64a08a85d584ce0c93&amp;dest_id=-75414&amp;dest_type=city&amp;group_adults=2&amp;group_children=0&amp;hapos=1&amp;hpos=1&amp;no_rooms=1&amp;sr_order=popularity&amp;srepoch=1576056398&amp;srpvid=f7a74266de280130&amp;ucfs=1&amp;from=searchresults;highlight_room=#hotelTmpl\">pagina Booking del Glamping Ribno<\/a>. Fidatevi di noi, non fatevelo scappare!<\/p>\n<h3>Una notte in un Traboule di Lione<\/h3>\n<div id=\"attachment_19589\" style=\"width: 294px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-19589\" class=\" wp-image-19589\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Traboule-Lyon-vacanze-di-Natale-2019-300x225.jpeg\" alt=\"Traboule Lyon vacanze di Natale 2019\" width=\"284\" height=\"213\" srcset=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Traboule-Lyon-vacanze-di-Natale-2019-300x225.jpeg 300w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Traboule-Lyon-vacanze-di-Natale-2019-768x576.jpeg 768w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Traboule-Lyon-vacanze-di-Natale-2019-800x600.jpeg 800w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Traboule-Lyon-vacanze-di-Natale-2019-700x525.jpeg 700w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Traboule-Lyon-vacanze-di-Natale-2019.jpeg 894w\" sizes=\"(max-width: 284px) 100vw, 284px\" \/><p id=\"caption-attachment-19589\" class=\"wp-caption-text\">Picture by Wikimedia Commons<\/p><\/div>\n<p>Lione \u00e8 una delle citt\u00e0 pi\u00f9 grandi della Francia, oltre ad essere un luogo veramente incantevole e con tantissime gemme da visitare. Il museo delle miniature e del cinema, Notre dame de Fourvi\u00e8re e un giro tra i murales de la Croix-Rousse sono solo alcuni dei punti imperdibili da visitare, ma la vera perla della citt\u00e0 sono i Traboules. Antiche costruzioni architettoniche tipiche del territorio, i Traboules sono passaggi sotterranei che permettono di passare da un punto ad un altro della citt\u00e0 senza dover necessariamente girare intorno agli edifici. La buona notizia? \u00c8 possibile pernottare all&#8217;interno di queste strutture!<br \/>\nSu AirBnB, sono tantissimi gli alloggi disponibili, e sono uno pi\u00f9 bello dell&#8217;altro. Il pi\u00f9 consigliato \u00e8 sicuramente l&#8217;<a href=\"https:\/\/www.airbnb.it\/rooms\/32682744?_set_bev_on_new_domain=1560410798_qd4LcLNMqmZ8g%2Fbo&amp;source_impression_id=p3_1576060263_8B8oO0eR7cBpi67S\">Atelier des Traboules<\/a>.. correte a dargli un&#8217;occhiata! Sar\u00e0 amore a prima vista.<\/p>\n<h3>Vacanze in riva al mare a Sestri Levante<\/h3>\n<p><img decoding=\"async\" class=\"size-medium wp-image-19590 alignleft\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/22228553_10210605288472858_2534270383348264125_n-300x224.jpg\" alt=\"Sestri Levante\" width=\"300\" height=\"224\" srcset=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/22228553_10210605288472858_2534270383348264125_n-300x224.jpg 300w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/22228553_10210605288472858_2534270383348264125_n-768x574.jpg 768w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/22228553_10210605288472858_2534270383348264125_n-800x600.jpg 800w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/22228553_10210605288472858_2534270383348264125_n-700x524.jpg 700w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/22228553_10210605288472858_2534270383348264125_n.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>Meta preferita dai milanesi durante il periodo estivo, Sestri Levante \u00e8 il luogo ideale dove trascorrere una vacanza anche durante il periodo natalizio. Il paese viene addobbato a festa in ogni suo angolo pi\u00f9 nascosto, e il mare \u00e8 talmente limpido che quasi non sembra vero.<br \/>\nQuesta \u00e8 la meta perfetta anche per chi adora mangiare. I ristorantini in cui ordinare piatti degni di uno chef sono infatti veramente tantissimi: a partire dalla Mattana, osteria tipica in cui mangiare tutti i piatti liguri pi\u00f9 tradizionali, fino al Pescador, uno dei migliori ristoranti di tutta la Riviera quando si tratta di pesce e crostacei.<br \/>\nChe siate alla ricerca di un albero o di una casa in cui alloggiare, Sestri ha una vastissima offerta che soddisfer\u00e0 qualunque vostra richiesta. Vi basta dare un occhio su Booking.com e su AirBnB!<\/p>\n<p>Tutti pronti a fare le valigie e partire?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Natale significa sempre tantissime cose: cibo, stare tra gli amici e in famiglia, lo scambio di regali, e anche qualche meritato giorno di ferie. Che siano di una settimana o solo di qualche giorno, le vacanze sono sempre il pretesto perfetto per staccare un attimo&#8230;<\/p>\n","protected":false},"author":3,"featured_media":19599,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":3,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vacanze di Natale last minute: tre idee per tutti i gusti - Robert Cutty<\/title>\n<meta name=\"description\" content=\"Non avete ancora prenotato le vacanze di Natale, ma state cominciando a sentire il bisogno di staccare la spina? Ecco tre mete che fanno al caso vostro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vacanze di Natale last minute: tre idee per tutti i gusti - Robert Cutty\" \/>\n<meta property=\"og:description\" content=\"Non avete ancora prenotato le vacanze di Natale, ma state cominciando a sentire il bisogno di staccare la spina? Ecco tre mete che fanno al caso vostro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute\" \/>\n<meta property=\"og:site_name\" content=\"Robert Cutty\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-13T09:01:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1350\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Tassoni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Tassoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#article\",\"isPartOf\":{\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute\"},\"author\":{\"name\":\"Giulia Tassoni\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\"},\"headline\":\"3 idee per una vacanza di Natale last minute\",\"datePublished\":\"2019-12-13T09:01:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute\"},\"wordCount\":579,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage\"},\"thumbnailUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute\",\"url\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute\",\"name\":\"Vacanze di Natale last minute: tre idee per tutti i gusti - Robert Cutty\",\"isPartOf\":{\"@id\":\"https:\/\/robertcutty.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage\"},\"image\":{\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage\"},\"thumbnailUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg\",\"datePublished\":\"2019-12-13T09:01:28+00:00\",\"author\":{\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\"},\"description\":\"Non avete ancora prenotato le vacanze di Natale, ma state cominciando a sentire il bisogno di staccare la spina? Ecco tre mete che fanno al caso vostro.\",\"breadcrumb\":{\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage\",\"url\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg\",\"contentUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg\",\"width\":1350,\"height\":900,\"caption\":\"Montagne e nuvole vacanze di Natale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/robertcutty.com\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 idee per una vacanza di Natale last minute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/robertcutty.com\/#website\",\"url\":\"https:\/\/robertcutty.com\/\",\"name\":\"Robert Cutty\",\"description\":\"Agenzia di comunicazione ed organizzazione eventi per adulti e bambini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/robertcutty.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\",\"name\":\"Giulia Tassoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g\",\"caption\":\"Giulia Tassoni\"},\"url\":\"https:\/\/robertcutty.com\/it\/author\/giulia-tassoni\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vacanze di Natale last minute: tre idee per tutti i gusti - Robert Cutty","description":"Non avete ancora prenotato le vacanze di Natale, ma state cominciando a sentire il bisogno di staccare la spina? Ecco tre mete che fanno al caso vostro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute","og_locale":"it_IT","og_type":"article","og_title":"Vacanze di Natale last minute: tre idee per tutti i gusti - Robert Cutty","og_description":"Non avete ancora prenotato le vacanze di Natale, ma state cominciando a sentire il bisogno di staccare la spina? Ecco tre mete che fanno al caso vostro.","og_url":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute","og_site_name":"Robert Cutty","article_published_time":"2019-12-13T09:01:28+00:00","og_image":[{"width":1350,"height":900,"url":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg","type":"image\/jpeg"}],"author":"Giulia Tassoni","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Tassoni","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#article","isPartOf":{"@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute"},"author":{"name":"Giulia Tassoni","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634"},"headline":"3 idee per una vacanza di Natale last minute","datePublished":"2019-12-13T09:01:28+00:00","mainEntityOfPage":{"@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute"},"wordCount":579,"commentCount":0,"image":{"@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage"},"thumbnailUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg","articleSection":["Non categorizzato"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#respond"]}]},{"@type":"WebPage","@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute","url":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute","name":"Vacanze di Natale last minute: tre idee per tutti i gusti - Robert Cutty","isPartOf":{"@id":"https:\/\/robertcutty.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage"},"image":{"@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage"},"thumbnailUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg","datePublished":"2019-12-13T09:01:28+00:00","author":{"@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634"},"description":"Non avete ancora prenotato le vacanze di Natale, ma state cominciando a sentire il bisogno di staccare la spina? Ecco tre mete che fanno al caso vostro.","breadcrumb":{"@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robertcutty.com\/vacanze-di-natale-last-minute"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#primaryimage","url":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg","contentUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/12\/Vacanze-di-Natale-2019-viaggi.jpeg","width":1350,"height":900,"caption":"Montagne e nuvole vacanze di Natale"},{"@type":"BreadcrumbList","@id":"https:\/\/robertcutty.com\/vacanze-di-natale-last-minute#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robertcutty.com\/it"},{"@type":"ListItem","position":2,"name":"3 idee per una vacanza di Natale last minute"}]},{"@type":"WebSite","@id":"https:\/\/robertcutty.com\/#website","url":"https:\/\/robertcutty.com\/","name":"Robert Cutty","description":"Agenzia di comunicazione ed organizzazione eventi per adulti e bambini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robertcutty.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634","name":"Giulia Tassoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g","caption":"Giulia Tassoni"},"url":"https:\/\/robertcutty.com\/it\/author\/giulia-tassoni"}]}},"_links":{"self":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/comments?post=19587"}],"version-history":[{"count":8,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19587\/revisions"}],"predecessor-version":[{"id":19598,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19587\/revisions\/19598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/media\/19599"}],"wp:attachment":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/media?parent=19587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/categories?post=19587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/tags?post=19587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}