{"id":19489,"date":"2019-11-22T09:04:10","date_gmt":"2019-11-22T09:04:10","guid":{"rendered":"https:\/\/robertcutty.com\/?p=19489"},"modified":"2019-11-26T14:56:52","modified_gmt":"2019-11-26T14:56:52","slug":"black-friday-2019-le-offerte-che-non-potete-farvi-scappare","status":"publish","type":"post","link":"https:\/\/robertcutty.com\/it\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare","title":{"rendered":"Black Friday 2019: le offerte che non potete farvi scappare"},"content":{"rendered":"<div id=\"attachment_19491\" style=\"width: 310px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-19491\" class=\"size-medium wp-image-19491\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/@crystaldisplays-300x300.jpg\" alt=\"Black Friday 2019 palloncino led\" width=\"300\" height=\"300\" srcset=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/@crystaldisplays-300x300.jpg 300w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/@crystaldisplays-150x150.jpg 150w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/@crystaldisplays.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-19491\" class=\"wp-caption-text\">Picture by \u00a9 Crystaldisplays<\/p><\/div>\n<p>\u00c8 dall&#8217;inizio di novembre che se ne sente parlare, e finalmente ci siamo quasi: manca esattamente una settimana al Black Friday, e le offerte delle quali si sente parlare sembrano veramente pazzesche. Sconti folli, saldi da tutte le parti e occasioni imperdibili sono un must della giornata dello shopping lampo, che diventa sempre l&#8217;occasione perfetta per comprare quel paio di scarpe o quel computer che puntavate da tanto.<\/p>\n<p>Nel mare di offerte dalle quali verremo sommersi la prossima settimana, queste sono le nostre preferite \ud83d\ude0d<\/p>\n<h3>Festeggia da RC Kids<\/h3>\n<p>Che sia per il compleanno del vostro bambino o per una cena di Natale con i compagni di classe, ogni occasione \u00e8 sempre buona per festeggiare \ud83c\udf8a<br \/>\nSe non stavate aspettando altro che la scusa perfetta per prenotare la vostra festa di compleanno, il Black Friday di <a href=\"https:\/\/robertcutty.com\/festa-di-compleanno-per-bambini-milano\">RC Kids<\/a> cade veramente a fagiolo.<br \/>\nCon lo sconto del 50% su tutti i plus, e il 20% sulle feste Deluxe del fine settimana (valido da luned\u00ec 25 novembre fino alla fine del 2020), potrete finalmente soddisfare la vostra voglia di party chic e sfarzosi.<\/p>\n<p>Ma le sorprese non finiscono qui. Con l&#8217;arrivo del Natale arriva anche il campus RC Kids, aperto a tutti i bimbi dai 3 ai 10 anni durante le giornate del 23, 27 e 30 dicembre 2019, e 2 e 3 gennaio 2020.<br \/>\nIl campus ha un costo di 50\u20ac al giorno, ma prenotando durante la Settimana del Black Friday (da luned\u00ec 25 novembre a domenica 1 dicembre) avrete uno sconto del 10% sulla singola giornata, e del 20% sul pacchetto di 5 giorni.<br \/>\nNon dimenticate che il pack che include tutte e 5 le giornate di campus \u00e8 condivisibile con i vostri amici!<\/p>\n<h3>Vola via per il week-end con Ryanair<\/h3>\n<p>Il Black Friday di Ryanair \u00e8 sempre uno degli eventi pi\u00f9 attesi da tutti gli amanti del viaggio. A differenza di molti altri brand, la compagnia irlandese non ha ancora spifferato nessuna informazione su quelle che saranno le offerte che ha in serbo per noi.<br \/>\nStando a quanto accaduto l&#8217;anno scorso per\u00f2, possiamo immaginare che ci saranno moltissimi posti al prezzo bloccato di 9,99\u20ac, insieme a molti altri con il 25% di sconto. In questo modo, diventer\u00e0 possibile raggiungere anche le mete pi\u00f9 lontane per prezzi letteralmente stracciati: un volo di andata e ritorno da Milano a Tel Aviv in Israele potrebbe arrivare a costare appena 30\u20ac, un&#8217;occasione alla quale non si pu\u00f2 assolutamente rinunciare.<\/p>\n<p>In ogni caso, vi suggeriamo di rimanere collegati al sito web di <a href=\"https:\/\/www.ryanair.com\/it\/it\/\">Ryanair<\/a> per scoprire tutti gli sconti in tempo reale! #staytuned<\/p>\n<div id=\"attachment_19496\" style=\"width: 310px\" class=\"wp-caption alignright\"><img decoding=\"async\" aria-describedby=\"caption-attachment-19496\" class=\"size-medium wp-image-19496\" src=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3-300x240.jpg\" alt=\"Black Friday scritta led\" width=\"300\" height=\"240\" srcset=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3-300x240.jpg 300w, https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg 563w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-19496\" class=\"wp-caption-text\">Picture by \u00a9 freepik<\/p><\/div>\n<h3>Shopping folle su Zalando<\/h3>\n<p>Tra le piattaforme e-commerce di moda e beauty pi\u00f9 amate al mondo, <a href=\"https:\/\/www.zalando.it\/\">Zalando<\/a> ha gi\u00e0 cominciato a dare qualche assaggio di quelli che saranno i suoi sconti del prossimo venerd\u00ec. Quello che ci si aspetta non sono solo grandi saldi sulle nuove collezioni dei principali marchi di moda, ma anche sconti cumulabili con quelli gi\u00e0 in atto. Insomma, non risparmiare sar\u00e0 impossibile (cos\u00ec come resistere dal comprare qualcosa del resto).<\/p>\n<p>Che venga anche offerta la spedizione gratuita sugli ordini di qualunque importo? Sarebbe la ciliegina sulla torta di un Black Friday pazzesco!<\/p>\n<h3>Le super offerte di Amazon<\/h3>\n<p>Celebre per offrire qualunque prodotto a un prezzo assolutamente imbattibile, <a href=\"https:\/\/www.amazon.it\/\">Amazon<\/a> ha in programma un Black Friday di promozioni veramente impareggiabili. Parendo dal presupposto che le offerte non saranno valide solamente durante la giornata del 29 Novembre, ma si protrarranno da luned\u00ec 25 novembre a fino a luned\u00ec 2 dicembre, gli sconti che avremo a disposizione ricoprono veramente qualunque sfera d&#8217;acquisto.<br \/>\nTra le offerte pi\u00f9 interessanti non si pu\u00f2 non citare i 4 mesi di Amazon Music Unlimited a 0,99\u20ac per i nuovi iscritti, un prezzo da urlo &#8211; oltre che a prova di competitor.<br \/>\nSaranno poi disponibili sconti su tantissimi prodotti targati Amazon, come Amazon Echo (che passer\u00e0 dai 79,99\u20ac del prezzo di listino a 64,99\u20ac), riduzioni fino al 25% sui prodotti tecnologici di Amazon Basics, e fino al 40% sui prodotti moda e beauty.<\/p>\n<p>Insomma, cominciate a preparare la vostra carta di credito.. se tutto andr\u00e0 come previsto, non avr\u00e0 un attimo di tregua \ud83d\ude0c<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 dall&#8217;inizio di novembre che se ne sente parlare, e finalmente ci siamo quasi: manca esattamente una settimana al Black Friday, e le offerte delle quali si sente parlare sembrano veramente pazzesche. Sconti folli, saldi da tutte le parti e occasioni imperdibili sono un must&#8230;<\/p>\n","protected":false},"author":3,"featured_media":19496,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":6,"footnotes":""},"categories":[282],"tags":[496,497,498,499,500,502,501],"class_list":["post-19489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-black-friday","tag-black-friday-2019","tag-black-week","tag-offerte","tag-promozioni","tag-saldi","tag-sconti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Black Friday 2019: le offerte che non potete farvi scappare - Robert Cutty<\/title>\n<meta name=\"description\" content=\"Ci siamo quasi: il Black Friday \u00e8 alle porte, e in giro si comincia a sentire aria di sconti. Scoprite con noi le offerte imperdibili di questo 29 novembre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Black Friday 2019: le offerte che non potete farvi scappare - Robert Cutty\" \/>\n<meta property=\"og:description\" content=\"Ci siamo quasi: il Black Friday \u00e8 alle porte, e in giro si comincia a sentire aria di sconti. Scoprite con noi le offerte imperdibili di questo 29 novembre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare\" \/>\n<meta property=\"og:site_name\" content=\"Robert Cutty\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-22T09:04:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-26T14:56:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"563\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giulia Tassoni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giulia Tassoni\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#article\",\"isPartOf\":{\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare\"},\"author\":{\"name\":\"Giulia Tassoni\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\"},\"headline\":\"Black Friday 2019: le offerte che non potete farvi scappare\",\"datePublished\":\"2019-11-22T09:04:10+00:00\",\"dateModified\":\"2019-11-26T14:56:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare\"},\"wordCount\":683,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage\"},\"thumbnailUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg\",\"keywords\":[\"black friday\",\"black friday 2019\",\"black week\",\"offerte\",\"promozioni\",\"saldi\",\"sconti\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare\",\"url\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare\",\"name\":\"Black Friday 2019: le offerte che non potete farvi scappare - Robert Cutty\",\"isPartOf\":{\"@id\":\"https:\/\/robertcutty.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage\"},\"image\":{\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage\"},\"thumbnailUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg\",\"datePublished\":\"2019-11-22T09:04:10+00:00\",\"dateModified\":\"2019-11-26T14:56:52+00:00\",\"author\":{\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\"},\"description\":\"Ci siamo quasi: il Black Friday \u00e8 alle porte, e in giro si comincia a sentire aria di sconti. Scoprite con noi le offerte imperdibili di questo 29 novembre.\",\"breadcrumb\":{\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage\",\"url\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg\",\"contentUrl\":\"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg\",\"width\":563,\"height\":450,\"caption\":\"Picture by \u00a9 freepik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/robertcutty.com\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Black Friday 2019: le offerte che non potete farvi scappare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/robertcutty.com\/#website\",\"url\":\"https:\/\/robertcutty.com\/\",\"name\":\"Robert Cutty\",\"description\":\"Agenzia di comunicazione ed organizzazione eventi per adulti e bambini\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/robertcutty.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634\",\"name\":\"Giulia Tassoni\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/robertcutty.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g\",\"caption\":\"Giulia Tassoni\"},\"url\":\"https:\/\/robertcutty.com\/it\/author\/giulia-tassoni\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Black Friday 2019: le offerte che non potete farvi scappare - Robert Cutty","description":"Ci siamo quasi: il Black Friday \u00e8 alle porte, e in giro si comincia a sentire aria di sconti. Scoprite con noi le offerte imperdibili di questo 29 novembre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare","og_locale":"it_IT","og_type":"article","og_title":"Black Friday 2019: le offerte che non potete farvi scappare - Robert Cutty","og_description":"Ci siamo quasi: il Black Friday \u00e8 alle porte, e in giro si comincia a sentire aria di sconti. Scoprite con noi le offerte imperdibili di questo 29 novembre.","og_url":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare","og_site_name":"Robert Cutty","article_published_time":"2019-11-22T09:04:10+00:00","article_modified_time":"2019-11-26T14:56:52+00:00","og_image":[{"width":563,"height":450,"url":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg","type":"image\/jpeg"}],"author":"Giulia Tassoni","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giulia Tassoni","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#article","isPartOf":{"@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare"},"author":{"name":"Giulia Tassoni","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634"},"headline":"Black Friday 2019: le offerte che non potete farvi scappare","datePublished":"2019-11-22T09:04:10+00:00","dateModified":"2019-11-26T14:56:52+00:00","mainEntityOfPage":{"@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare"},"wordCount":683,"commentCount":0,"image":{"@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage"},"thumbnailUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg","keywords":["black friday","black friday 2019","black week","offerte","promozioni","saldi","sconti"],"articleSection":["Eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#respond"]}]},{"@type":"WebPage","@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare","url":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare","name":"Black Friday 2019: le offerte che non potete farvi scappare - Robert Cutty","isPartOf":{"@id":"https:\/\/robertcutty.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage"},"image":{"@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage"},"thumbnailUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg","datePublished":"2019-11-22T09:04:10+00:00","dateModified":"2019-11-26T14:56:52+00:00","author":{"@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634"},"description":"Ci siamo quasi: il Black Friday \u00e8 alle porte, e in giro si comincia a sentire aria di sconti. Scoprite con noi le offerte imperdibili di questo 29 novembre.","breadcrumb":{"@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#primaryimage","url":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg","contentUrl":"https:\/\/robertcutty.com\/wp-content\/uploads\/2019\/11\/b8f2b40c3bac7be237c036ccb22050c3.jpg","width":563,"height":450,"caption":"Picture by \u00a9 freepik"},{"@type":"BreadcrumbList","@id":"https:\/\/robertcutty.com\/black-friday-2019-le-offerte-che-non-potete-farvi-scappare#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robertcutty.com\/it"},{"@type":"ListItem","position":2,"name":"Black Friday 2019: le offerte che non potete farvi scappare"}]},{"@type":"WebSite","@id":"https:\/\/robertcutty.com\/#website","url":"https:\/\/robertcutty.com\/","name":"Robert Cutty","description":"Agenzia di comunicazione ed organizzazione eventi per adulti e bambini","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robertcutty.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/42b79bd8ffd9121ef7a5affcd691f634","name":"Giulia Tassoni","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/robertcutty.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9da91c415b3378fe0a6662b269d676a911e6691d680c7789875b6495ef0e014b?s=96&d=mm&r=g","caption":"Giulia Tassoni"},"url":"https:\/\/robertcutty.com\/it\/author\/giulia-tassoni"}]}},"_links":{"self":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/comments?post=19489"}],"version-history":[{"count":8,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19489\/revisions"}],"predecessor-version":[{"id":19499,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/posts\/19489\/revisions\/19499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/media\/19496"}],"wp:attachment":[{"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/media?parent=19489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/categories?post=19489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertcutty.com\/it\/wp-json\/wp\/v2\/tags?post=19489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}